{"id":36,"count":0,"description":"","link":"https:\/\/refreshedelectronics.com\/index.php\/product-category\/accessories\/","name":"Accessories","slug":"accessories","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/refreshedelectronics.com\/index.php\/wp-json\/wp\/v2\/product_cat\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/refreshedelectronics.com\/index.php\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/refreshedelectronics.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/refreshedelectronics.com\/index.php\/wp-json\/wp\/v2\/product?product_cat=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}