{"id":49,"count":2,"description":"","link":"https:\/\/refreshedelectronics.com\/index.php\/product-category\/laptop-replacement-parts\/lcds-assembly\/","name":"LCDs Assembly","slug":"lcds-assembly","taxonomy":"product_cat","parent":38,"meta":[],"_links":{"self":[{"href":"https:\/\/refreshedelectronics.com\/index.php\/wp-json\/wp\/v2\/product_cat\/49","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/refreshedelectronics.com\/index.php\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/refreshedelectronics.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/refreshedelectronics.com\/index.php\/wp-json\/wp\/v2\/product_cat\/38"}],"wp:post_type":[{"href":"https:\/\/refreshedelectronics.com\/index.php\/wp-json\/wp\/v2\/product?product_cat=49"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}