{"id":58,"count":1,"description":"","link":"https:\/\/refreshedelectronics.com\/index.php\/product-category\/desktop-replacement-parts\/caddies\/","name":"Caddies","slug":"caddies","taxonomy":"product_cat","parent":24,"meta":[],"_links":{"self":[{"href":"https:\/\/refreshedelectronics.com\/index.php\/wp-json\/wp\/v2\/product_cat\/58","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/refreshedelectronics.com\/index.php\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/refreshedelectronics.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/refreshedelectronics.com\/index.php\/wp-json\/wp\/v2\/product_cat\/24"}],"wp:post_type":[{"href":"https:\/\/refreshedelectronics.com\/index.php\/wp-json\/wp\/v2\/product?product_cat=58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}